{"id":137,"date":"2014-12-30T12:39:27","date_gmt":"2014-12-30T11:39:27","guid":{"rendered":"https:\/\/vwg.nl\/uncategorized\/periodieke-gift\/"},"modified":"2026-03-03T10:32:24","modified_gmt":"2026-03-03T09:32:24","slug":"regelmasige-spende","status":"publish","type":"post","link":"https:\/\/vwg.nl\/de\/periodieke-gift\/","title":{"rendered":"Regelm\u00e4\u00dfige Spende"},"content":{"rendered":"<p>Der Staatssekret\u00e4r f\u00fcr Finanzen hat den Erlass \u00fcber Spenden und gemeinn\u00fctzige Organisationen (ANBI) erg\u00e4nzt. Dies ist eine gute Gelegenheit, die vielleicht etwas (zu) unbekannte M\u00f6glichkeit regelm\u00e4\u00dfiger Spenden erneut zu erl\u00e4utern.<\/p>\n<p>Schenkungen an ein ANBI k\u00f6nnen erfolgen als <em>pers\u00f6nliche Abz\u00fcge<\/em> werden von dem Einkommen abgezogen, auf das die Einkommensteuer erhoben wird. Ein ANBI ist eine Einrichtung, die als solche in dem von den Steuerbeh\u00f6rden zu diesem Zweck gef\u00fchrten Register aufgef\u00fchrt ist. Die Website <strong>ANBI-Register<\/strong> finden Sie <a title=\"hier\" href=\"http:\/\/www.belastingdienst.nl\/wps\/wcm\/connect\/bldcontentnl\/themaoverstijgend\/rekenhulpen\/programma_anbi_opzoeken\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<br \/>\nDamit der Abzug wirksam wird, muss der Gesamtbetrag der Spenden an ANBIs in einem Kalenderjahr einen Schwellenwert \u00fcberschreiten. Dieser Schwellenwert betr\u00e4gt 1% des gemeinsamen Gesamteinkommens des Steuerpflichtigen und seines Steuerpartners (der Schwellenwert liegt bei mindestens 60 \u20ac). Das Gesamteinkommen ist die Summe der Eink\u00fcnfte in den Feldern 1, 2 und 3. \u00dcbersteigt die Gesamtsumme der Spenden 10% des Gesamteinkommens, darf der \u00dcberschuss nicht abgezogen werden.<\/p>\n<p>Sowohl der Schwellenwert als auch der H\u00f6chstwert gelten nicht, wenn ein <strong>regelm\u00e4\u00dfige Spende<\/strong>. Diese Spende ist vom ersten Euro an abzugsf\u00e4hig, und wenn die Summe der regelm\u00e4\u00dfigen Spenden in einem Jahr 10% des (gemeinsamen) Gesamteinkommens \u00fcbersteigt, ist auch der \u00dcberschuss abzugsf\u00e4hig. Ein weiterer Vorteil der regelm\u00e4\u00dfigen Spenden ist, dass sie nicht nur abzugsf\u00e4hig sind, wenn sie an eine ANBI geleistet werden, sondern auch, wenn sie an nicht k\u00f6rperschaftsteuerpflichtige Vereine mit mindestens 25 Mitgliedern geleistet werden. Dies macht die regelm\u00e4\u00dfige Spende zu einem interessanten Instrument f\u00fcr (Sport-)Vereine, da der Fiskus z. B. den Bau eines (Kunstrasen-)Platzes oder die Einrichtung von Kantinen und Umkleider\u00e4umen mitfinanzieren kann.<\/p>\n<p>Eine periodische Schenkung muss mindestens 5 Jahre lang laufen. Es sei denn, der Schenker stirbt; dann muss die Schenkung enden. In einem neuen Abschnitt des vorgenannten Dekrets wurden einige Ausnahmen formuliert. Es ist erlaubt, die regelm\u00e4\u00dfige Schenkung innerhalb der 5-Jahres-Frist zu beenden, wenn der Schenker arbeitsunf\u00e4hig oder arbeitslos ist. Eine vorzeitige Beendigung ist auch zul\u00e4ssig, wenn die beschenkte Einrichtung in Konkurs geht oder ihren ANBI-Status verliert. Denn ab dem Zeitpunkt, an dem die Einrichtung nicht mehr im ANBI-Register der Steuerverwaltung eingetragen ist, sind die Raten der regelm\u00e4\u00dfigen Schenkung nicht mehr abzugsf\u00e4hig (der Erlass enth\u00e4lt eine Genehmigung f\u00fcr regelm\u00e4\u00dfige Schenkungen an ANBI, die ihren ANBI-Status aufgrund der \u00c4nderung der ANBI-Regelung zum 1.2.2010 verloren haben). Es ist unter keinen Umst\u00e4nden erlaubt, bereits abgelaufene Raten einer regelm\u00e4\u00dfigen Spende r\u00fcckg\u00e4ngig zu machen (zu widerrufen). Die Beendigung einer regelm\u00e4\u00dfigen Spende darf nur die zu diesem Zeitpunkt noch nicht abgelaufenen Raten betreffen.<\/p>\n<p>Beim Tod des Schenkers kann der Schenker testamentarisch bestimmen, dass die am Todestag noch f\u00e4lligen Raten der wiederkehrenden Schenkung in Form eines Verm\u00e4chtnisses aus dem Nachlass des Schenkers in einer Summe ausgezahlt werden. Dies ist insbesondere bei einer regelm\u00e4\u00dfigen Sachschenkung (z. B. eines Kunstwerks oder Sammlerst\u00fccks an ein Museum) der Fall, aber auch bei einer regelm\u00e4\u00dfigen Geldschenkung zul\u00e4ssig.<br \/>\nEs ist nicht zul\u00e4ssig, im Schenkungsvertrag (oder in einer gesonderten Vereinbarung) die Kapitalabfindung auf den Tod des Schenkers festzulegen.<\/p>\n<p>Seit 2014 muss eine regelm\u00e4\u00dfige Schenkung nicht mehr in einer notariellen Urkunde festgehalten werden, sondern nur noch auf einem Formular, das die Steuerbeh\u00f6rden zu diesem Zweck zur Verf\u00fcgung stellen, vollst\u00e4ndig ausgef\u00fcllt werden. Damit ist es interessant geworden, auch kleinere Betr\u00e4ge in Form einer regelm\u00e4\u00dfigen Schenkung zu machen. Dieses Formular finden Sie <a title=\"hier\" href=\"http:\/\/www.belastingdienst.nl\/wps\/wcm\/connect\/bldcontentnl\/themaoverstijgend\/programmas_en_formulieren\/overeenkomst_periodieke_giften\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>De Staatssecretaris van Financi\u00ebn heeft het besluit over giften en algemeen nut beogende instellingen (ANBI) aangevuld. Dat is een mooie gelegenheid om de wellicht wat (te) onbekende mogelijkheid van periodieke giften nog eens toe te lichten. Giften aan een ANBI mogen als persoonsgebonden aftrek worden afgetrokken van het inkomen waarover inkomstenbelasting is verschuldigd. Een ANBI [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-137","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/posts\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":1,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"predecessor-version":[{"id":2150,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/posts\/137\/revisions\/2150"}],"wp:attachment":[{"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vwg.nl\/de\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}